{"id":144,"date":"2025-07-11T16:39:43","date_gmt":"2025-07-11T16:39:43","guid":{"rendered":"https:\/\/luxurytours.pt\/?page_id=144"},"modified":"2025-09-02T10:59:19","modified_gmt":"2025-09-02T10:59:19","slug":"portugal","status":"publish","type":"page","link":"https:\/\/luxurytours.pt\/fr\/portugal\/","title":{"rendered":"Portugal"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"144\" class=\"elementor elementor-144\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-196c9ed e-flex e-con-boxed e-con e-parent\" data-id=\"196c9ed\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c331f8e e-con-full e-flex e-con e-child\" data-id=\"c331f8e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b38ef8d elementor-widget elementor-widget-heading\" data-id=\"b38ef8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9couvrir le Portugal<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bed07d9 elementor-widget elementor-widget-text-editor\" data-id=\"bed07d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Beaut\u00e9 intemporelle, culture riche et exp\u00e9riences inoubliables<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d23cc9b elementor-widget elementor-widget-text-editor\" data-id=\"d23cc9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Des c\u00f4tes dor\u00e9es aux ch\u00e2teaux de contes de f\u00e9es, le Portugal est une terre d'\u00e9merveillement qui ne demande qu'\u00e0 \u00eatre explor\u00e9e. Chez Luxury Tours Portugal, nous vous invitons \u00e0 d\u00e9couvrir l'\u00e2me de ce pays dynamique gr\u00e2ce \u00e0 des visites guid\u00e9es d'une journ\u00e9e et \u00e0 des exp\u00e9riences de voyage exclusives. Que vous vous promeniez dans les rues pav\u00e9es de Sintra, que vous sirotiez des vins dans les collines d'Azeit\u00e3o ou que vous observiez les dauphins au large de Sesimbra, nos circuits vont bien au-del\u00e0 de l'ordinaire.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09538cc elementor-align-center elementor-widget elementor-widget-button\" data-id=\"09538cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/luxurytours.pt\/fr\/ourtours\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-long-arrow-alt-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.941 216H12c-6.627 0-12 5.373-12 12v56c0 6.627 5.373 12 12 12h301.941v46.059c0 21.382 25.851 32.09 40.971 16.971l86.059-86.059c9.373-9.373 9.373-24.569 0-33.941l-86.059-86.059c-15.119-15.119-40.971-4.411-40.971 16.971V216z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir tous les circuits<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a2bda36 e-flex e-con-boxed e-con e-parent\" data-id=\"a2bda36\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-27bf13a e-con-full e-flex e-con e-child\" data-id=\"27bf13a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b245fd8 e-con-full e-flex e-con e-child\" data-id=\"b245fd8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5716c45 elementor-widget elementor-widget-shortcode\" data-id=\"5716c45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n\t\t\t\t\t<!-- Start Fullwidth Wrap -->\n\t\t\t<div class=\"tf_tf_booking-widget-wrap\" data-fullwidth=\"true\">\n\t\t\t\t<div class=\"tf_custom-container\">\n\t\t\t\t\t<div class=\"tf_custom-inner\">\n\n\t\t\t\t\t\t\t\t\t\t<div id=\"tf-booking-search-tabs\" class=\"location, default-form tf-search-tabs__design--1\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<!-- Booking Form Tabs -->\n\t\t\t\t\t\t<div class=\"tf-booking-form-tab design-1\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t<!-- Booking Forms -->\n\t\t\t\t\t\t<div class=\"tf-booking-forms-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"tf-tour-booking-form\" class=\"tf-tabcontent\" style=\"display:block\">\n\t\t\t\t\t\t\t\t\t            <form class=\"tf_booking-widget location, default-form\" id=\"tf_tour_aval_check\" method=\"get\" autocomplete=\"off\" action=\"https:\/\/luxurytours.pt\/fr\/tf-search\/\" data-trp-original-action=\"https:\/\/luxurytours.pt\/fr\/tf-search\/\">\n                <div class=\"tf_homepage-booking\">\n\t\t\t\t\t                        <div class=\"tf_destination-wrap\">\n                            <div class=\"tf_input-inner\">\n                                <div class=\"tf_form-row\">\n                                    <label class=\"tf_label-row\">\n                                        <span class=\"tf-label\">Destination :<\/span>\n                                        <div class=\"tf_form-inner\">\n                                            <div class=\"tf-search-form-field-icon\">\n                                                <i class=\"fas fa-search\"><\/i>\n                                            <\/div>\n\t\t\t\t\t\t\t\t\t\t\t                                                <input type=\"text\" name=\"place-name\"  id=\"tf-destination\" class=\"\"\n                                                       placeholder=\"Entrer la destination\" value=\"\">\n                                                <input type=\"hidden\" name=\"place\" id=\"tf-search-tour\" class=\"tf-place-input\"\/>\n\t\t\t\t\t\t\t\t\t\t\t                                        <\/div>\n                                    <\/label>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n                    <div class=\"tf_selectperson-wrap\">\n                        <div class=\"tf_input-inner\">\n                        <span class=\"tf_person-icon tf-search-form-field-icon\">\n                            <i class=\"fas fa-user\"><\/i>\n                        <\/span>\n                            <div class=\"adults-text\">1 Adultes<\/div>\n\t\t\t\t\t\t\t                                <div class=\"person-sep\"><\/div>\n                                <div class=\"child-text\">0 Enfants<\/div>\n\t\t\t\t\t\t\t                                <div class=\"person-sep\"><\/div>\n                                <div class=\"infant-text\">0 Nourrisson<\/div>\n\t\t\t\t\t\t\t                        <\/div>\n                        <div class=\"tf_acrselection-wrap\">\n                            <div class=\"tf_acrselection-inner\">\n                                <div class=\"tf_acrselection\">\n                                    <div class=\"acr-label\">Adultes<\/div>\n                                    <div class=\"acr-select\">\n                                        <div class=\"acr-dec\">-<\/div>\n                                        <input type=\"number\" name=\"adults\" id=\"adults\" min=\"1\" value=\"1\">\n                                        <div class=\"acr-inc\">+<\/div>\n                                    <\/div>\n                                <\/div>\n\t\t\t\t\t\t\t\t                                    <div class=\"tf_acrselection\">\n                                        <div class=\"acr-label\">Les enfants<\/div>\n                                        <div class=\"acr-select\">\n                                            <div class=\"acr-dec\">-<\/div>\n                                            <input type=\"number\" name=\"children\" id=\"children\" min=\"0\" value=\"0\">\n                                            <div class=\"acr-inc\">+<\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t                                    <div class=\"tf_acrselection\">\n                                        <div class=\"acr-label\">Nourrisson<\/div>\n                                        <div class=\"acr-select\">\n                                            <div class=\"acr-dec\">-<\/div>\n                                            <input type=\"number\" name=\"infant\" id=\"infant\" min=\"0\" value=\"0\">\n                                            <div class=\"acr-inc\">+<\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t                            <\/div>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"tf_selectdate-wrap\">\n                        <!-- @KK Merged two inputs into one  -->\n                        <div class=\"tf_input-inner\">\n                            <label class=\"tf_label-row\">\n\t                                <span class=\"tf-label\">Dates de d\u00e9but et de fin<\/span>\n                                <div class=\"tf_form-inner\">\n                                    <div class=\"tf-search-form-field-icon\">\n                                        <i class=\"far fa-calendar-alt\"><\/i>\n                                    <\/div>\n                                    <input type=\"text\" name=\"check-in-out-date\" id=\"check-in-out-date\" onkeypress=\"return false;\"\n                                           placeholder=\"S\u00e9lectionner la date\" required>\n                                <\/div>\n                            <\/label>\n                        <\/div>\n                    <\/div>\n\n\t\t\t\t\t\n                    <div class=\"tf_submit-wrap\">\n                        <input type=\"hidden\" name=\"type\" value=\"tf_tours\" class=\"tf-post-type\"\/>\n\t\t\t\t\t\t                        <button class=\"tf_btn tf-submit\" type=\"submit\">Recherche<\/button>\n                    <\/div>\n\n                <\/div>\n\n            <input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form>\n            <script>\n                (function ($) {\n                    $(document).ready(function () {\n\n\t\t\t\t\t\tconst regexMap = {\n                            'Y\/m\/d': \/(\\d{4}\\\/\\d{2}\\\/\\d{2}).*(\\d{4}\\\/\\d{2}\\\/\\d{2})\/,\n                            'd\/m\/Y': \/(\\d{2}\\\/\\d{2}\\\/\\d{4}).*(\\d{2}\\\/\\d{2}\\\/\\d{4})\/,\n                            'm\/d\/Y': \/(\\d{2}\\\/\\d{2}\\\/\\d{4}).*(\\d{2}\\\/\\d{2}\\\/\\d{4})\/,\n                            'Y-m-d': \/(\\d{4}-\\d{2}-\\d{2}).*(\\d{4}-\\d{2}-\\d{2})\/,\n                            'd-m-Y': \/(\\d{2}-\\d{2}-\\d{4}).*(\\d{2}-\\d{2}-\\d{4})\/,\n                            'm-d-Y': \/(\\d{2}-\\d{2}-\\d{4}).*(\\d{2}-\\d{2}-\\d{4})\/,\n                            'Y.m.d': \/(\\d{4}\\.\\d{2}\\.\\d{2}).*(\\d{4}\\.\\d{2}\\.\\d{2})\/,\n                            'd.m.Y': \/(\\d{2}\\.\\d{2}\\.\\d{4}).*(\\d{2}\\.\\d{2}\\.\\d{4})\/,\n                            'm.d.Y': \/(\\d{2}\\.\\d{2}\\.\\d{4}).*(\\d{2}\\.\\d{2}\\.\\d{4})\/\n                        };\n                        const dateRegex = regexMap['d\/m\/Y'];\n\n                        \/\/ flatpickr first day of Week\n\t\t\t\t\t\twindow.flatpickr.l10ns.fr.firstDayOfWeek = 1\n                        $(\"#tf_tour_aval_check #check-in-out-date\").flatpickr({\n                            enableTime: false,\n                            mode: \"range\",\n                            altInput: true,\n                            dateFormat: \"Y\/m\/d\",\n                            altFormat: 'd\/m\/Y',\n                            minDate: \"today\",\n\n                            \/\/ flatpickr locale\n\t\t\t\t\t\t\tlocale: \"fr\",\n                            onReady: function (selectedDates, dateStr, instance) {\n                                instance.element.value = dateStr.replace(\/(\\d{4}\\\/\\d{2}\\\/\\d{2}).*(\\d{4}\\\/\\d{2}\\\/\\d{2})\/g, function (match, date1, date2) {\n\t\t\t\t\t\t\t\treturn `${date1} - ${date2}`;\n\t\t\t\t\t\t\t\t});\n\t\t\t\t\t\t\t\tinstance.altInput.value = instance.altInput.value.replace( dateRegex, function (match, d1, d2) {\n\t\t\t\t\t\t\t\t\treturn `${d1} - ${d2}`;\n\t\t\t\t\t\t\t\t});\n                            },\n                            onChange: function (selectedDates, dateStr, instance) {\n                                instance.element.value = dateStr.replace(\/(\\d{4}\\\/\\d{2}\\\/\\d{2}).*(\\d{4}\\\/\\d{2}\\\/\\d{2})\/g, function (match, date1, date2) {\n\t\t\t\t\t\t\t\t\treturn `${date1} - ${date2}`;\n\t\t\t\t\t\t\t\t});\n\t\t\t\t\t\t\t\tinstance.altInput.value = instance.altInput.value.replace( dateRegex, function (match, d1, d2) {\n\t\t\t\t\t\t\t\t\treturn `${d1} - ${d2}`;\n\t\t\t\t\t\t\t\t});\n                            },\n                        });\n\n                    });\n                })(jQuery);\n            <\/script>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<!-- Close Fullwidth Wrap -->\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1758eab e-flex e-con-boxed e-con e-parent\" data-id=\"1758eab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1ddafe5 e-con-full e-flex e-con e-child\" data-id=\"1ddafe5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4e12cae e-con-full e-flex e-con e-child\" data-id=\"4e12cae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd382f5 elementor-widget elementor-widget-text-editor\" data-id=\"bd382f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous cr\u00e9ons des moments immersifs qui vous mettent en contact avec le vrai Portugal - ses saveurs, ses histoires, ses paysages et ses habitants.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-714d304 elementor-widget elementor-widget-heading\" data-id=\"714d304\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Pourquoi visiter le Portugal ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d972ec elementor-widget elementor-widget-text-editor\" data-id=\"5d972ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Le Portugal est plus qu'une simple destination : c'est un voyage \u00e0 travers le temps et la culture, envelopp\u00e9 d'une hospitalit\u00e9 chaleureuse et d'un charme m\u00e9diterran\u00e9en. Voici pourquoi les voyageurs du monde entier tombent amoureux du Portugal :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5659b1d elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5659b1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Un climat doux tout au long de l'ann\u00e9e - Avec plus de 300 jours de soleil par an, le Portugal est parfait pour des aventures en plein air \u00e0 tout moment.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Des paysages vari\u00e9s - Des montagnes luxuriantes et des falaises aux vignobles et aux plages de sable, chaque r\u00e9gion est unique.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sites historiques - Explorez les ch\u00e2teaux, les palais, les ruines romaines, l'architecture mauresque et les villes s\u00e9culaires.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cuisine et vins de classe mondiale - D\u00e9gustez des plats embl\u00e9matiques comme le bacalhau et le pastel de nata, accompagn\u00e9s de vins locaux prim\u00e9s.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cuisine et vins de classe mondiale - D\u00e9gustez des plats embl\u00e9matiques comme le bacalhau et le pastel de nata, accompagn\u00e9s de vins locaux prim\u00e9s.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Proximit\u00e9 de Lisbonne - De nombreux joyaux du pays se trouvent \u00e0 une courte distance en voiture de la capitale.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a5bc7d elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"9a5bc7d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3266fd0c\" data-id=\"3266fd0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2dd8ef31 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2dd8ef31\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-14377bd0\" data-id=\"14377bd0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f12a41 elementor-widget elementor-widget-image-carousel\" data-id=\"8f12a41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d&#039;images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-6-r8qnczjpjdu0uygu6p7sfnxflb5aaihxt1tzi92afs.webp\" alt=\"Portugal (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-7-r8qnd0hjq7vb6kfh17mf05ow6p0ni7lo56hgzj0w9k.webp\" alt=\"Portugal (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-8-r8qnd0hjq7vb6kfh17mf05ow6p0ni7lo56hgzj0w9k.webp\" alt=\"Portugal (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-9-r8qnd0hjq7vb6kfh17mf05ow6p0ni7lo56hgzj0w9k.webp\" alt=\"Portugal (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-10-r8qnd1fdx1wli6e3vq11kngcs2w0pwpehb4ygszi3c.webp\" alt=\"Portugal (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-2-r8qncylvcjsqjci7c6t5v65yzx9x2te7gx6i0z3om0.webp\" alt=\"Portugal (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-3-1-r8qncylvcjsqjci7c6t5v65yzx9x2te7gx6i0z3om0.webp\" alt=\"Portugal (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-4-1-r8qnczjpjdu0uygu6p7sfnxflb5aaihxt1tzi92afs.webp\" alt=\"Portugal (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-1-r8qnd1fdx1wli6e3vq11kngcs2w0pwpehb4ygszi3c.webp\" alt=\"Portugal\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-5-r8qnczjpjdu0uygu6p7sfnxflb5aaihxt1tzi92afs.webp\" alt=\"Portugal (5)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4faeedec\" data-id=\"4faeedec\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cceda26 elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"2cceda26\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d&#039;images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 10\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2cceda26\" data-elementor-lightbox-title=\"Portugal\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDkzLCJ1cmwiOiJodHRwczpcL1wvbHV4dXJ5dG91cnMucHRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcL1BvcnR1Z2FsLTEud2VicCIsInNsaWRlc2hvdyI6IjJjY2VkYTI2In0%3D\" href=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-1.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-1-r8qnd1fdx1wli6e3vq11kngcs2w0pwpehb4ygszi3c.webp\" alt=\"Portugal\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 10\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2cceda26\" data-elementor-lightbox-title=\"Portugal (10)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDkyLCJ1cmwiOiJodHRwczpcL1wvbHV4dXJ5dG91cnMucHRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcL1BvcnR1Z2FsLTEwLndlYnAiLCJzbGlkZXNob3ciOiIyY2NlZGEyNiJ9\" href=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-10.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-10-r8qnd1fdx1wli6e3vq11kngcs2w0pwpehb4ygszi3c.webp\" alt=\"Portugal (10)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 10\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2cceda26\" data-elementor-lightbox-title=\"Portugal (9)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDkxLCJ1cmwiOiJodHRwczpcL1wvbHV4dXJ5dG91cnMucHRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcL1BvcnR1Z2FsLTkud2VicCIsInNsaWRlc2hvdyI6IjJjY2VkYTI2In0%3D\" href=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-9.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-9-r8qnd0hjq7vb6kfh17mf05ow6p0ni7lo56hgzj0w9k.webp\" alt=\"Portugal (9)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 10\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2cceda26\" data-elementor-lightbox-title=\"Portugal (7)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDg5LCJ1cmwiOiJodHRwczpcL1wvbHV4dXJ5dG91cnMucHRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcL1BvcnR1Z2FsLTcud2VicCIsInNsaWRlc2hvdyI6IjJjY2VkYTI2In0%3D\" href=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-7.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-7-r8qnd0hjq7vb6kfh17mf05ow6p0ni7lo56hgzj0w9k.webp\" alt=\"Portugal (7)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 10\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2cceda26\" data-elementor-lightbox-title=\"Portugal (6)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDg4LCJ1cmwiOiJodHRwczpcL1wvbHV4dXJ5dG91cnMucHRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcL1BvcnR1Z2FsLTYud2VicCIsInNsaWRlc2hvdyI6IjJjY2VkYTI2In0%3D\" href=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-6.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-6-r8qnczjpjdu0uygu6p7sfnxflb5aaihxt1tzi92afs.webp\" alt=\"Portugal (6)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 10\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2cceda26\" data-elementor-lightbox-title=\"Portugal (5)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDg3LCJ1cmwiOiJodHRwczpcL1wvbHV4dXJ5dG91cnMucHRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcL1BvcnR1Z2FsLTUud2VicCIsInNsaWRlc2hvdyI6IjJjY2VkYTI2In0%3D\" href=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-5.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-5-r8qnczjpjdu0uygu6p7sfnxflb5aaihxt1tzi92afs.webp\" alt=\"Portugal (5)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 10\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2cceda26\" data-elementor-lightbox-title=\"Portugal (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDg2LCJ1cmwiOiJodHRwczpcL1wvbHV4dXJ5dG91cnMucHRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcL1BvcnR1Z2FsLTQtMS53ZWJwIiwic2xpZGVzaG93IjoiMmNjZWRhMjYifQ%3D%3D\" href=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-4-1.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-4-1-r8qnczjpjdu0uygu6p7sfnxflb5aaihxt1tzi92afs.webp\" alt=\"Portugal (4)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 10\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2cceda26\" data-elementor-lightbox-title=\"Portugal (8)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDkwLCJ1cmwiOiJodHRwczpcL1wvbHV4dXJ5dG91cnMucHRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcL1BvcnR1Z2FsLTgud2VicCIsInNsaWRlc2hvdyI6IjJjY2VkYTI2In0%3D\" href=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-8.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-8-r8qnd0hjq7vb6kfh17mf05ow6p0ni7lo56hgzj0w9k.webp\" alt=\"Portugal (8)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 10\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2cceda26\" data-elementor-lightbox-title=\"Portugal (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDg1LCJ1cmwiOiJodHRwczpcL1wvbHV4dXJ5dG91cnMucHRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcL1BvcnR1Z2FsLTMtMS53ZWJwIiwic2xpZGVzaG93IjoiMmNjZWRhMjYifQ%3D%3D\" href=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-3-1.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-3-1-r8qncylvcjsqjci7c6t5v65yzx9x2te7gx6i0z3om0.webp\" alt=\"Portugal (3)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 10\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2cceda26\" data-elementor-lightbox-title=\"Portugal (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDg0LCJ1cmwiOiJodHRwczpcL1wvbHV4dXJ5dG91cnMucHRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcL1BvcnR1Z2FsLTIud2VicCIsInNsaWRlc2hvdyI6IjJjY2VkYTI2In0%3D\" href=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-2.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-2-r8qncylvcjsqjci7c6t5v65yzx9x2te7gx6i0z3om0.webp\" alt=\"Portugal (2)\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5eb4e3f4\" data-id=\"5eb4e3f4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a0099fc elementor-widget elementor-widget-image-carousel\" data-id=\"3a0099fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d&#039;images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-2-r8qncylvcjsqjci7c6t5v65yzx9x2te7gx6i0z3om0.webp\" alt=\"Portugal (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-3-1-r8qncylvcjsqjci7c6t5v65yzx9x2te7gx6i0z3om0.webp\" alt=\"Portugal (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-4-1-r8qnczjpjdu0uygu6p7sfnxflb5aaihxt1tzi92afs.webp\" alt=\"Portugal (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-5-r8qnczjpjdu0uygu6p7sfnxflb5aaihxt1tzi92afs.webp\" alt=\"Portugal (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-9-r8qnd0hjq7vb6kfh17mf05ow6p0ni7lo56hgzj0w9k.webp\" alt=\"Portugal (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-7-r8qnd0hjq7vb6kfh17mf05ow6p0ni7lo56hgzj0w9k.webp\" alt=\"Portugal (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-8-r8qnd0hjq7vb6kfh17mf05ow6p0ni7lo56hgzj0w9k.webp\" alt=\"Portugal (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-10-r8qnd1fdx1wli6e3vq11kngcs2w0pwpehb4ygszi3c.webp\" alt=\"Portugal (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-6-r8qnczjpjdu0uygu6p7sfnxflb5aaihxt1tzi92afs.webp\" alt=\"Portugal (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/elementor\/thumbs\/Portugal-1-r8qnd1fdx1wli6e3vq11kngcs2w0pwpehb4ygszi3c.webp\" alt=\"Portugal\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-a27d226 e-flex e-con-boxed e-con e-parent\" data-id=\"a27d226\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-123d282 e-con-full e-flex e-con e-child\" data-id=\"123d282\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-45ffdbe e-con-full e-flex e-con e-child\" data-id=\"45ffdbe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-047d963 elementor-widget elementor-widget-heading\" data-id=\"047d963\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le meilleur du Portugal - \u00e0 votre fa\u00e7on<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58b21c1 elementor-widget elementor-widget-text-editor\" data-id=\"58b21c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Luxury Tours Portugal propose des excursions d'une journ\u00e9e au d\u00e9part de Lisbonne, guid\u00e9es par des experts, et des excursions priv\u00e9es qui r\u00e9v\u00e8lent la profondeur et la diversit\u00e9 du pays :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7eec710 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7eec710\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sintra et Cascais Explorez des palais de conte de f\u00e9es, comme le palais de Pena, et promenez-vous dans les charmants villages de Cascais et d'Estoril. Visitez Cabo da Roca, le point le plus \u00e0 l'ouest de l'Europe, et sentez les vents de l'Atlantique balayer les falaises spectaculaires.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sesimbra et Azeit\u00e3o Combinez aventure et culture avec une excursion d'observation des dauphins, une d\u00e9gustation de vins locaux dans les caves historiques d'Azeit\u00e3o et un atelier pratique de peinture sur carreaux. N'oubliez pas le d\u00e9jeuner de fruits de mer frais avec vue sur l'oc\u00e9an.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lisbonne &amp; Croisi\u00e8res au coucher du soleil D\u00e9couvrez la capitale sous un nouvel angle lors d'une croisi\u00e8re relaxante au coucher du soleil, en passant devant la tour de Bel\u00e9m, le pont du 25 avril et la majestueuse statue du Christ-Roi. Cette croisi\u00e8re est id\u00e9ale pour les amoureux et les f\u00eatards.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b19b96 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7b19b96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/luxurytours.pt\/fr\/ourtours\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-long-arrow-alt-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.941 216H12c-6.627 0-12 5.373-12 12v56c0 6.627 5.373 12 12 12h301.941v46.059c0 21.382 25.851 32.09 40.971 16.971l86.059-86.059c9.373-9.373 9.373-24.569 0-33.941l-86.059-86.059c-15.119-15.119-40.971-4.411-40.971 16.971V216z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir tous les circuits<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73a0873 e-flex e-con-boxed e-con e-parent\" data-id=\"73a0873\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e1d581d e-con-full e-flex e-con e-child\" data-id=\"e1d581d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-881e08f elementor-widget elementor-widget-heading\" data-id=\"881e08f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9couvrez le Portugal \u00e0 la mani\u00e8re de Luxury Tours<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bd8804 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1bd8804\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Notre mission est de vous emmener plus loin - au-del\u00e0 des pi\u00e8ges \u00e0 touristes et des circuits en bus - et de vous faire d\u00e9couvrir l'\u00e2me du Portugal. Lorsque vous voyagez avec nous, vous obtenez :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64e1934 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"64e1934\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-dot-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 56c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m0-48C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 168c-44.183 0-80 35.817-80 80s35.817 80 80 80 80-35.817 80-80-35.817-80-80-80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Des circuits sur mesure adapt\u00e9s \u00e0 votre rythme et \u00e0 vos centres d'int\u00e9r\u00eat<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-dot-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 56c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m0-48C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 168c-44.183 0-80 35.817-80 80s35.817 80 80 80 80-35.817 80-80-35.817-80-80-80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Des formats priv\u00e9s et en petits groupes pour une exp\u00e9rience plus intime<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-dot-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 56c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m0-48C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 168c-44.183 0-80 35.817-80 80s35.817 80 80 80 80-35.817 80-80-35.817-80-80-80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Des guides experts locaux qui donnent vie \u00e0 l'histoire et \u00e0 la culture<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-dot-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 56c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m0-48C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 168c-44.183 0-80 35.817-80 80s35.817 80 80 80 80-35.817 80-80-35.817-80-80-80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Transport confortable avec Wi-Fi et bouteilles d'eau<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-dot-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 56c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m0-48C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 168c-44.183 0-80 35.817-80 80s35.817 80 80 80 80-35.817 80-80-35.817-80-80-80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Acc\u00e8s aux joyaux cach\u00e9s, aux artisans locaux et aux saveurs authentiques<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a10ccff elementor-widget elementor-widget-text-editor\" data-id=\"a10ccff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous ne nous contentons pas de vous montrer le Portugal, nous vous le faisons sentir.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f0aec48 e-con-full elementor-hidden-tablet e-flex e-con e-child\" data-id=\"f0aec48\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4cddfc animated-slow elementor-arrows-position-inside elementor-pagination-position-outside elementor-invisible elementor-widget elementor-widget-image-carousel\" data-id=\"d4cddfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d&#039;images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-11.webp\" alt=\"Portugal 11\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-12.webp\" alt=\"Portugal 12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-13.webp\" alt=\"Portugal 13\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-14.webp\" alt=\"Portugal 14\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-15.webp\" alt=\"Portugal 15\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-16.webp\" alt=\"Portugal 16\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-17.webp\" alt=\"Portugal 17\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-18.webp\" alt=\"Portugal 18\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-19.webp\" alt=\"Portugal 19\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 10\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/luxurytours.pt\/wp-content\/uploads\/Portugal-20.webp\" alt=\"Portugal 20\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez le Portugal Beaut\u00e9 intemporelle, culture riche et exp\u00e9riences inoubliables Des c\u00f4tes dor\u00e9es aux ch\u00e2teaux de contes de f\u00e9es, le Portugal est un pays merveilleux qui ne demande qu'\u00e0 \u00eatre explor\u00e9. Chez Luxury Tours Portugal, nous vous invitons \u00e0 d\u00e9couvrir l'\u00e2me de ce pays dynamique gr\u00e2ce \u00e0 des visites guid\u00e9es d'une journ\u00e9e et \u00e0 des exp\u00e9riences de voyage exclusives. Que vous vous promeniez dans les rues pav\u00e9es...<\/p>","protected":false},"author":1,"featured_media":755,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-144","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/luxurytours.pt\/fr\/wp-json\/wp\/v2\/pages\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luxurytours.pt\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/luxurytours.pt\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/luxurytours.pt\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/luxurytours.pt\/fr\/wp-json\/wp\/v2\/comments?post=144"}],"version-history":[{"count":52,"href":"https:\/\/luxurytours.pt\/fr\/wp-json\/wp\/v2\/pages\/144\/revisions"}],"predecessor-version":[{"id":1086,"href":"https:\/\/luxurytours.pt\/fr\/wp-json\/wp\/v2\/pages\/144\/revisions\/1086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luxurytours.pt\/fr\/wp-json\/wp\/v2\/media\/755"}],"wp:attachment":[{"href":"https:\/\/luxurytours.pt\/fr\/wp-json\/wp\/v2\/media?parent=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}